{"id":238007,"date":"2025-01-22T14:47:44","date_gmt":"2025-01-22T13:47:44","guid":{"rendered":"https:\/\/www.ritzy.ch\/course\/dejouer-les-pieges-et-dangers-sur-internet\/"},"modified":"2026-05-13T22:29:32","modified_gmt":"2026-05-13T20:29:32","slug":"dejouer-les-pieges-et-dangers-sur-internet","status":"publish","type":"course","link":"https:\/\/www.ritzy.ch\/fr\/course\/dejouer-les-pieges-et-dangers-sur-internet\/","title":{"rendered":"D\u00e9jouer les pi\u00e8ges et dangers sur Internet"},"content":{"rendered":"<p>Nous sommes constamment connect\u00e9s avec Internet en priv\u00e9 ou au travail, sur un ordinateur ou sur un mobile, que ce soit pour la recherche d\u2019information, l\u2019email, les r\u00e9seaux sociaux ou encore le chat en direct via des syst\u00e8mes comme Skype, Teams ou Whatsapp. Les agressions pour vol de donn\u00e9es ou publicit\u00e9 non souhait\u00e9e ou encore l\u2019usurpation de donn\u00e9es sensibles sont monnaies courantes.<\/p>\n","protected":false},"featured_media":242671,"template":"","meta":{"_acf_changed":false},"course-category":[249],"course-tag":[467,468],"class_list":["post-238007","course","type-course","status-publish","has-post-thumbnail","hentry","course-category-catinfo","course-tag-467","course-tag-presentiel"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/course\/238007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/types\/course"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/media\/242671"}],"wp:attachment":[{"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/media?parent=238007"}],"wp:term":[{"taxonomy":"course-category","embeddable":true,"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/course-category?post=238007"},{"taxonomy":"course-tag","embeddable":true,"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/course-tag?post=238007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}