{"id":238902,"date":"2025-01-22T15:06:21","date_gmt":"2025-01-22T14:06:21","guid":{"rendered":"https:\/\/www.ritzy.ch\/course\/lpd-pour-les-hoteliers-restaurateurs-comment-mettre-en-pratique\/"},"modified":"2026-05-13T23:15:03","modified_gmt":"2026-05-13T21:15:03","slug":"lpd-pour-les-hoteliers-restaurateurs-comment-mettre-en-pratique","status":"publish","type":"course","link":"https:\/\/www.ritzy.ch\/fr\/course\/lpd-pour-les-hoteliers-restaurateurs-comment-mettre-en-pratique\/","title":{"rendered":"LPD pour les h\u00f4teliers &#8211; Restaurateurs : Comment mettre en pratique"},"content":{"rendered":"<p>Profitez de cet atelier pour remplir les principaux documents n\u00e9cessaires \u00e0 mettre en conformit\u00e9 avec la nouvelle Loi sur la protection des donn\u00e9es (LPD), en vigueur en Suisse depuis le 1er septembre 2023, ainsi qu\u2019avec le R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD) de l\u2019UE. A la fin de cet atelier, vous aurez r\u00e9fl\u00e9chi sur les donn\u00e9es que vous utilisez quotidiennement, vous aurez des mod\u00e8les de document \u00e0 remplir, et une checklist d\u2019actions \u00e0 entreprendre pour \u00eatre en r\u00e8gle.<\/p>\n","protected":false},"featured_media":243640,"template":"","meta":{"_acf_changed":false},"course-category":[249],"course-tag":[467,468],"class_list":["post-238902","course","type-course","status-publish","has-post-thumbnail","hentry","course-category-catinfo","course-tag-467","course-tag-presentiel"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/course\/238902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/types\/course"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/media\/243640"}],"wp:attachment":[{"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/media?parent=238902"}],"wp:term":[{"taxonomy":"course-category","embeddable":true,"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/course-category?post=238902"},{"taxonomy":"course-tag","embeddable":true,"href":"https:\/\/www.ritzy.ch\/fr\/wp-json\/wp\/v2\/course-tag?post=238902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}